{"id":99,"date":"2023-12-14T12:06:23","date_gmt":"2023-12-14T11:06:23","guid":{"rendered":"https:\/\/www.fermesaintsimeon.fr\/?page_id=99"},"modified":"2026-07-20T15:10:20","modified_gmt":"2026-07-20T13:10:20","slug":"servizi","status":"publish","type":"page","link":"https:\/\/www.fermesaintsimeon.fr\/it\/services\/","title":{"rendered":"Presentazione degli Spazi e dei Servizi"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"99\" class=\"elementor elementor-99\" data-elementor-post-type=\"page\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1698319 overflow-hidden-xs e-flex e-con-boxed e-con e-parent\" data-id=\"1698319\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e7e7fdd bg-full-section-xs e-flex e-con-boxed e-con e-child\" data-id=\"e7e7fdd\" data-element_type=\"container\" data-e-type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-abbd98b elementor-absolute e-transform evt-tache-gauche elementor-widget elementor-widget-image\" data-id=\"abbd98b\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:100,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"618\" height=\"424\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco.png\" class=\"attachment-large size-large wp-image-1142\" alt=\"\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco.png 618w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco-300x206.png 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco-18x12.png 18w\" sizes=\"(max-width: 618px) 100vw, 618px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-248322d elementor-absolute e-transform evt-tache-droite elementor-widget elementor-widget-image\" data-id=\"248322d\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;_position&quot;:&quot;absolute&quot;,&quot;_transform_rotateZ_effect&quot;:{&quot;unit&quot;:&quot;px&quot;,&quot;size&quot;:108,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_laptop&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_tablet&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]},&quot;_transform_rotateZ_effect_mobile&quot;:{&quot;unit&quot;:&quot;deg&quot;,&quot;size&quot;:&quot;&quot;,&quot;sizes&quot;:[]}}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"618\" height=\"424\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco.png\" class=\"attachment-large size-large wp-image-1142\" alt=\"\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco.png 618w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco-300x206.png 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/tache-deco-18x12.png 18w\" sizes=\"(max-width: 618px) 100vw, 618px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f31d68f event-titre elementor-widget elementor-widget-heading\" data-id=\"f31d68f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Il<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a89fcef event-titre elementor-widget elementor-widget-heading\" data-id=\"a89fcef\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<div class=\"elementor-heading-title elementor-size-default\">Presentazione degli Spazi e dei Servizi<\/div>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-9c85006 e-flex e-con-boxed e-con e-parent\" data-id=\"9c85006\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-006e890 e-con-full e-flex e-con e-child\" data-id=\"006e890\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-9132321 e-flex e-con-boxed e-con e-child\" data-id=\"9132321\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-8841705 elementor-widget elementor-widget-heading\" data-id=\"8841705\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">UN HOTEL SCELTO A HONFLEUR<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-eac020f elementor-widget elementor-widget-heading\" data-id=\"eac020f\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Bambini e neonati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-367bc69 elementor-widget elementor-widget-text-editor\" data-id=\"367bc69\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Accogliamo calorosamente i nostri giovani ospiti.<br \/>I vostri figli dai 4 ai 12 anni hanno bisogno di una sistemazione? La struttura storica dei nostri edifici ci consente di aggiungere un letto aggiuntivo in alcune camere. Vi preghiamo di contattare il nostro team delle prenotazioni per trovare la soluzione pi\u00f9 adatta al vostro soggiorno in famiglia.<br \/>State viaggiando con un bambino sotto i 3 anni? Metteremo a vostra disposizione gratuitamente una culla nella vostra camera (su richiesta e previa disponibilit\u00e0).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-59e76e4 e-con-full e-flex e-con e-child\" data-id=\"59e76e4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4bf3f8b elementor-widget__width-initial left-to-right elementor-widget elementor-widget-image\" data-id=\"4bf3f8b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1402396844-683x1024.jpg\" class=\"attachment-large size-large wp-image-5332\" alt=\"ragazzo e ragazza biondi su una chaise longue di vimini - hotel honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1402396844-683x1024.jpg 683w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1402396844-200x300.jpg 200w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1402396844-768x1152.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1402396844-8x12.jpg 8w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1402396844.jpg 836w\" sizes=\"(max-width: 683px) 100vw, 683px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-f275f3a e-flex e-con-boxed e-con e-parent\" data-id=\"f275f3a\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-28dd35b e-con-full e-flex e-con e-child\" data-id=\"28dd35b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e13ac87 elementor-widget__width-initial right-to-left elementor-widget elementor-widget-image\" data-id=\"e13ac87\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-1024x683.jpg\" class=\"attachment-large size-large wp-image-6664\" alt=\"\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-1024x683.jpg 1024w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-300x200.jpg 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-768x512.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-1536x1024.jpg 1536w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-2048x1365.jpg 2048w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2025\/02\/Laurent-portrait-2-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-44739b1 e-con-full e-flex e-con e-child\" data-id=\"44739b1\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-5d55a5f e-flex e-con-boxed e-con e-child\" data-id=\"5d55a5f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-87aefb3 elementor-widget elementor-widget-heading\" data-id=\"87aefb3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Concierge<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-372065d elementor-widget elementor-widget-text-editor\" data-id=\"372065d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Il nostro concierge, Laurent Dauvert, accoglie tutti i nostri ospiti con un servizio eccellente.<br \/>Originario di Honfleur, <span class=\"il\">Laurent<\/span> ha forgiato la sua esperienza attraverso una carriera di grande successo nel settore alberghiero di lusso, viaggiando da Parigi a Nizza, <br \/>Saint-Barth\u00e9lemy, Bora Bora e Aix-en-Provence, prima di entrare nel nostro hotel come concierge Cl\u00e9fs d'Or.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-6a91b43 e-flex e-con-boxed e-con e-parent\" data-id=\"6a91b43\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-70c1265 e-con-full e-flex e-con e-child\" data-id=\"70c1265\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-c5035fb e-flex e-con-boxed e-con e-child\" data-id=\"c5035fb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-ea7318b elementor-widget elementor-widget-heading\" data-id=\"ea7318b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Picnic chic<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3ac4a82 elementor-widget elementor-widget-text-editor\" data-id=\"3ac4a82\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per gli amanti delle escursioni all'aria aperta o delle scoperte storiche, il nostro Chef e il suo team possono preparare un delizioso picnic per voi. Partite con la mente tranquilla per una giornata di avventura!<br \/>Prezzo: 50 euro a persona<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-970823e elementor-align-center elementor-widget elementor-widget-button\" data-id=\"970823e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm elementor-animation-float\" href=\"https:\/\/www.menumodo.com\/app.php\/viewer\/outlet\/7816\/27171?lang=en&amp;tags=h\" rel=\"nofollow noopener\" target=\"_blank\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Menu<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-edd354b e-con-full e-flex e-con e-child\" data-id=\"edd354b\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-01cf7cc elementor-widget__width-initial left-to-right elementor-widget elementor-widget-image\" data-id=\"01cf7cc\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1388180166-1024x683.jpg\" class=\"attachment-large size-large wp-image-5331\" alt=\"colazione al sacco con cialde e t\u00e8 - hotel honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1388180166-1024x683.jpg 1024w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1388180166-300x200.jpg 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1388180166-768x512.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1388180166-18x12.jpg 18w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1388180166.jpg 1254w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-991fff5 e-flex e-con-boxed e-con e-parent\" data-id=\"991fff5\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-10075eb e-con-full e-flex e-con e-child\" data-id=\"10075eb\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-62352bd elementor-widget__width-initial right-to-left elementor-widget elementor-widget-image\" data-id=\"62352bd\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Cours-de-peinture-1024x683.png\" class=\"attachment-large size-large wp-image-4620\" alt=\"lezioni di pittura alla Ferme Saint Sim\u00e9on - relais et chateaux honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Cours-de-peinture-1024x683.png 1024w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Cours-de-peinture-300x200.png 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Cours-de-peinture-768x512.png 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Cours-de-peinture-18x12.png 18w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Cours-de-peinture.png 1498w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-be8eed9 e-con-full e-flex e-con e-child\" data-id=\"be8eed9\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-168a959 e-flex e-con-boxed e-con e-child\" data-id=\"168a959\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-896f204 elementor-widget elementor-widget-heading\" data-id=\"896f204\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Corsi di Pittura ad Acquerello<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-aa33ae6 elementor-widget elementor-widget-text-editor\" data-id=\"aa33ae6\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per dare sfogo al vostro lato impressionista a Honfleur, La Ferme Saint Sim\u00e9on offre corsi di pittura ad acquerello condotti da un artista locale.<br \/>L'artista ospiter\u00e0 gli ospiti artisti della Ferme Saint Sim\u00e9on per una lezione di pittura di 2 ore che si terr\u00e0 nella sua galleria (sul posto), nei giardini o di fronte all'estuario, a seconda del tempo.<br \/>Prezzo: 150 euro a persona<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c2d1ee e-flex e-con-boxed e-con e-parent\" data-id=\"1c2d1ee\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-e716f96 e-con-full e-flex e-con e-child\" data-id=\"e716f96\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-7a76d50 e-flex e-con-boxed e-con e-child\" data-id=\"7a76d50\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6d14ebe elementor-widget elementor-widget-heading\" data-id=\"6d14ebe\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tour Guidati<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-0f3e3c3 elementor-widget elementor-widget-text-editor\" data-id=\"0f3e3c3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Trascorrere una giornata con una guida \u00e8 il miglior modo per scoprire i segreti di una regione. Potrete decidere insieme alla guida, prima della partenza, quali siti desiderate visitare.<br \/>Tour disponibili in francese, inglese, russo e spagnolo.<br \/>Contattate il nostro concierge per informazioni: concierge@fermesaintsimeon.fr<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-4b6242e e-con-full e-flex e-con e-child\" data-id=\"4b6242e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-10c6bed elementor-widget__width-initial left-to-right elementor-widget elementor-widget-image\" data-id=\"10c6bed\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"534\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-1024x683.jpg\" class=\"attachment-large size-large wp-image-4655\" alt=\"porto vecchio di Honfleur - relais et chateaux honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-1024x683.jpg 1024w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-300x200.jpg 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-768x512.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-1536x1024.jpg 1536w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-2048x1365.jpg 2048w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/iStock-844088332-18x12.jpg 18w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-54e2c05 e-flex e-con-boxed e-con e-parent\" data-id=\"54e2c05\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-aa073f6 e-con-full e-flex e-con e-child\" data-id=\"aa073f6\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-7d5a510 elementor-widget__width-initial right-to-left elementor-widget elementor-widget-image\" data-id=\"7d5a510\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"683\" height=\"1024\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-683x1024.jpg\" class=\"attachment-large size-large wp-image-4622\" alt=\"tour in auto d&#039;epoca - hotel honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-683x1024.jpg 683w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-200x300.jpg 200w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-768x1152.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-1024x1536.jpg 1024w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-1366x2048.jpg 1366w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-8x12.jpg 8w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Balade-en-classic-car-2-scaled.jpg 1707w\" sizes=\"(max-width: 683px) 100vw, 683px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-c022122 e-con-full e-flex e-con e-child\" data-id=\"c022122\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b473b01 e-flex e-con-boxed e-con e-child\" data-id=\"b473b01\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-6c611a3 elementor-widget elementor-widget-heading\" data-id=\"6c611a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Tour in Auto d'Epoca<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-bdd646c elementor-widget elementor-widget-text-editor\" data-id=\"bdd646c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per una gita con gli amici, un weekend romantico o una vacanza in famiglia, noleggiate un'auto d'epoca e vivete momenti indimenticabili esplorando le strade pi\u00f9 belle della Normandia.<br \/>Concedetevi un'esperienza di guida di lusso con famosi veicoli come la Ford Thunderbird di Marilyn Monroe, la Porsche 356 di James Dean, l'Austin-Healey di Brigitte Bardot o la Morgan di Ralph Lauren.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-ca9b812 e-flex e-con-boxed e-con e-parent\" data-id=\"ca9b812\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-ed8b75e e-con-full e-flex e-con e-child\" data-id=\"ed8b75e\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-b0e8b92 e-flex e-con-boxed e-con e-child\" data-id=\"b0e8b92\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-4756be3 elementor-widget elementor-widget-heading\" data-id=\"4756be3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Sessioni di kitesurf e wingsurf<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c9921c7 elementor-widget elementor-widget-text-editor\" data-id=\"c9921c7\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Con la sua costa unica caratterizzata da ampie spiagge di sabbia e ciottoli, la nostra magnifica regione della Normandia consente la pratica di vari sport acquatici, tra cui il kitesurf, il windsurf, la vela, il jet ski e le uscite in barca con uno skipper.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-13a210a elementor-widget elementor-widget-n-accordion\" data-id=\"13a210a\" data-element_type=\"widget\" data-e-type=\"widget\" data-settings=\"{&quot;default_state&quot;:&quot;all_collapsed&quot;,&quot;max_items_expended&quot;:&quot;one&quot;,&quot;n_accordion_animation_duration&quot;:{&quot;unit&quot;:&quot;ms&quot;,&quot;size&quot;:400,&quot;sizes&quot;:[]}}\" data-widget_type=\"nested-accordion.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"e-n-accordion\" aria-label=\"Fisarmonica. Aprite i collegamenti con Invio o Spazio, chiudeteli con Escape e navigate con i tasti freccia.\">\n\t\t\t\t\t\t<details id=\"e-n-accordion-item-2050\" class=\"e-n-accordion-item\" >\n\t\t\t\t<summary class=\"e-n-accordion-item-title\" data-accordion-index=\"1\" tabindex=\"0\" aria-expanded=\"false\" aria-controls=\"e-n-accordion-item-2050\" >\n\t\t\t\t\t<span class='e-n-accordion-item-title-header'><div class=\"e-n-accordion-item-title-text\"> Pi\u00f9 informazioni <\/div><\/span>\n\t\t\t\t\t\t\t<span class='e-n-accordion-item-title-icon'>\n\t\t\t<span class='e-opened' ><i aria-hidden=\"true\" class=\"fas fa-minus\"><\/i><\/span>\n\t\t\t<span class='e-closed'><i aria-hidden=\"true\" class=\"fas fa-plus\"><\/i><\/span>\n\t\t<\/span>\n\n\t\t\t\t\t\t<\/summary>\n\t\t\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2050\" class=\"elementor-element elementor-element-e355689 e-con-full e-flex e-con e-child\" data-id=\"e355689\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div role=\"region\" aria-labelledby=\"e-n-accordion-item-2050\" class=\"elementor-element elementor-element-5a27d54 e-flex e-con-boxed e-con e-child\" data-id=\"5a27d54\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-66439d9 elementor-widget elementor-widget-text-editor\" data-id=\"66439d9\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Per i nostri ospiti esperti di kitesurf e wingsurf che vogliono viaggiare leggeri, possiamo fornire attrezzature professionali per kitesurf e wingsurf per scoprire gli spot nei dintorni di Honfleur: Trouville e la sua famosa spiaggia storica, Le Havre e il suo wave spot, Antifer e le sue scogliere uniche o Merville-Franceville per un kitesurf sicuro.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-49db49d elementor-widget elementor-widget-text-editor\" data-id=\"49db49d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Vi invitiamo a contattare il nostro concierge per saperne di pi\u00f9 su questa attivit\u00e0: <a href=\"mailto:kitesurf@fermesaintsimeon.fr\">kitesurf@fermesaintsimeon.fr<\/a><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/details>\n\t\t\t\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-884c9fc e-con-full e-flex e-con e-child\" data-id=\"884c9fc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c7bd51d elementor-widget__width-initial left-to-right elementor-widget elementor-widget-image\" data-id=\"c7bd51d\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"710\" height=\"1024\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1169772598-710x1024.jpg\" class=\"attachment-large size-large wp-image-5334\" alt=\"tramonto e kitesurf sulla spiaggia di Saint-Malo in Bretagna - hotel honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1169772598-710x1024.jpg 710w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1169772598-208x300.jpg 208w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1169772598-768x1107.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1169772598-8x12.jpg 8w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1169772598.jpg 853w\" sizes=\"(max-width: 710px) 100vw, 710px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-225ebca e-flex e-con-boxed e-con e-parent\" data-id=\"225ebca\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-642c3aa e-con-full e-flex e-con e-child\" data-id=\"642c3aa\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a533dc4 e-flex e-con-boxed e-con e-child\" data-id=\"a533dc4\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-c06b3c0 elementor-widget elementor-widget-heading\" data-id=\"c06b3c0\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Trasferimenti e navette<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1b186af elementor-widget elementor-widget-text-editor\" data-id=\"1b186af\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Servizio di navetta tra gli aeroporti Charles de Gaulle \/ Orly e l'hotel (andata o andata e ritorno).<br \/>Trasporto privato con autista (massimo 4 persone).<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e692362 elementor-widget__width-initial right-to-left elementor-widget elementor-widget-image\" data-id=\"e692362\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"512\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1695488119-768x512.jpg\" class=\"attachment-medium_large size-medium_large wp-image-5335\" alt=\"persone sedute in un minivan taxi - hotel honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1695488119-768x512.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1695488119-300x200.jpg 300w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1695488119-1024x683.jpg 1024w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1695488119-18x12.jpg 18w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/02\/iStock-1695488119.jpg 1253w\" sizes=\"(max-width: 768px) 100vw, 768px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-81878cf e-flex e-con-boxed e-con e-parent\" data-id=\"81878cf\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-bf9d16f e-con-full e-flex e-con e-child\" data-id=\"bf9d16f\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-e8b15ba elementor-widget__width-initial right-to-left elementor-widget elementor-widget-image\" data-id=\"e8b15ba\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"1000\" src=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-819x1024.jpg\" class=\"attachment-large size-large wp-image-4626\" alt=\"colazione a buffet con miele prodotto nella fattoria Saint Sim\u00e9on - hotel honfleur\" srcset=\"https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-819x1024.jpg 819w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-240x300.jpg 240w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-768x960.jpg 768w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-1229x1536.jpg 1229w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-1638x2048.jpg 1638w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-10x12.jpg 10w, https:\/\/www.fermesaintsimeon.fr\/wp-content\/uploads\/2024\/01\/Buffet-6-scaled.jpg 2048w\" sizes=\"(max-width: 800px) 100vw, 800px\" title=\"\">\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-eb4e577 e-con-full e-flex e-con e-child\" data-id=\"eb4e577\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-610f2cc e-flex e-con-boxed e-con e-child\" data-id=\"610f2cc\" data-element_type=\"container\" data-e-type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-908a6a3 elementor-widget elementor-widget-heading\" data-id=\"908a6a3\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Miele alla Ferme Saint Sim\u00e9on<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-3272c38 elementor-widget elementor-widget-text-editor\" data-id=\"3272c38\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Da alcune settimane, il nostro hotel a Honfleur ospita quasi 300.000 api distribuite in 4 arnie.<br \/>Impegnati nello sviluppo sostenibile, produciamo il nostro miele per deliziare i nostri ospiti con un sapore molto locale!<br \/>Godetevi il nostro miele nei vostri piatti e a colazione, poi portate a casa un vasetto di miele disponibile in vendita nella nostra boutique.<br \/>Questa aggiunta completa le nostre altre iniziative a lungo termine, come la selezione di partner locali per ridurre la nostra impronta di carbonio, la produzione di succo di mele dai nostri frutteti, la fornitura di acqua potabile per gli hotel dalle nostre sorgenti e il nostro orto di erbe aromatiche...<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Les Services UN H\u00d4TEL DE CHOIX \u00c0 HONFLEUR\u200b Enfants et b\u00e9b\u00e9s Nos petits h\u00f4tes sont accueillis avec grand plaisir.Vos enfants ont entre 4 et 12 ans ? La disposition historique des b\u00e2timents nous permet d&rsquo;ajouter un lit suppl\u00e9mentaire dans quelques chambres. Nous vous invitons \u00e0 vous rapprocher de notre service r\u00e9servations pour trouver la solution [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-99","page","type-page","status-publish","hentry"],"_links":{"self":[{"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/pages\/99","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/comments?post=99"}],"version-history":[{"count":82,"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/pages\/99\/revisions"}],"predecessor-version":[{"id":7667,"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/pages\/99\/revisions\/7667"}],"wp:attachment":[{"href":"https:\/\/www.fermesaintsimeon.fr\/it\/wp-json\/wp\/v2\/media?parent=99"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}